{"id":20254,"date":"2020-08-03T14:17:35","date_gmt":"2020-08-03T17:17:35","guid":{"rendered":"https:\/\/centoevinte.com.br\/portal-de-conteudo\/?p=20254"},"modified":"2022-08-17T09:44:37","modified_gmt":"2022-08-17T12:44:37","slug":"3-kpis-em-marketing-digital","status":"publish","type":"post","link":"https:\/\/centoevinte.com.br\/portal-de-conteudo\/3-kpis-em-marketing-digital\/","title":{"rendered":"3 KPIs em marketing digital e s\u00e3o apenas eles que IMPORTAM!"},"content":{"rendered":"<figure><\/figure>\n<figure><\/figure>\n<p>O cen\u00e1rio de marketing est\u00e1 se tornando cada vez mais complexo. Hoje, uma ORGANIZA\u00c7\u00c3O deve considerar uma ampla gama de op\u00e7\u00f5es para divulgar sua empresa. Os canais mais tradicionais, como <strong>an\u00fancios on-line<\/strong>, <strong>e-mail<\/strong> e <strong>marketing de conte\u00fado<\/strong>, est\u00e3o em constante evolu\u00e7\u00e3o e novas tecnologias, como por exemplo, VR est\u00e3o chegando muito em breve.<\/p>\n<p>Embora o cen\u00e1rio de marketing seja complexo, eu gostaria de argumentar que, quando se trata de medir o desempenho de marketing, \u00e9 preciso ser realmente MUITO direto. Neste post, vou ensinar como voc\u00ea pode usar os dados para determinar facilmente se sua equipe de marketing est\u00e1 atingindo seus objetivos.<\/p>\n<blockquote><p><strong>&#8220;Onde h\u00e1 fuma\u00e7a de dados, h\u00e1 inc\u00eandio nos neg\u00f3cios.&#8221; &#8211; Thomas Redman<\/strong><\/p><\/blockquote>\n<h2 id=\"0-what-is-the-primary-goal-of-the-marketing-team\">Qual \u00e9 o objetivo principal da equipe de marketing? Focar em KPIs em Marketing Digital!<\/h2>\n<p>Antes de podermos investigar o desempenho da equipe de marketing, precisamos entender seu objetivo principal.<\/p>\n<p>O objetivo principal de uma equipe de marketing \u00e9 ajudar a empresa a aumentar as vendas. Atinge esse objetivo, oferecendo mais oportunidades para que as vendas sejam feitas. Isso ocorre na forma de conectar indiv\u00edduos a representantes de vendas (marketing de gera\u00e7\u00e3o de leads) ou expor mais indiv\u00edduos diretamente aos produtos e servi\u00e7os da empresa (modelo freemium).<\/p>\n<p>Em ambos os casos, tudo se resume a expor a marca a um n\u00famero cada vez maior de indiv\u00edduos. <em><strong>Em outras palavras, podemos medir o desempenho da equipe de marketing medindo o reconhecimento da marca.<\/strong><\/em><\/p>\n<p>J\u00e1 consigo ouvir seus pensamentos, \u201cmas Justin, e a taxa de convers\u00e3o? Certamente o reconhecimento da marca n\u00e3o \u00e9 a \u00fanica coisa que importa. \u201d Voc\u00ea estaria correto ao dizer que a taxa de convers\u00e3o \u00e9 importante, mas eu diria que a equipe de marketing tem um pequeno papel a desempenhar quando se trata da taxa geral de convers\u00e3o de visitante ou lead, para cliente.<\/p>\n<p>Voc\u00ea pode testar a A \/ B at\u00e9 a morte e escrever o melhor conte\u00fado do mundo, mas se voc\u00ea n\u00e3o tiver um ajuste no mercado do produto, a equipe de marketing poder\u00e1 fazer pouco. Eu argumentaria que os fundadores, produtos, P&amp;D e vendas t\u00eam um impacto muito maior na convers\u00e3o do que a equipe de marketing. A exce\u00e7\u00e3o seria o sistema de mensagens usado para comunicar sobre a empresa e seu posicionamento no mercado, mas isso deve ser resolvido pelos fundadores antes da forma\u00e7\u00e3o de uma equipe de marketing.<\/p>\n<p>Para simplificar, vamos supor que a empresa tenha um ajuste no mercado do produto e um funil de convers\u00e3o decente.<\/p>\n<h2>Os KPIs de marketing\u00a0de desempenho para sua a equipe<\/h2>\n<p>Ent\u00e3o, agora que definimos o objetivo principal da equipe de marketing, podemos escrever alguns KPIs de <a href=\"https:\/\/dbt.marketing\/\" target=\"_blank\" rel=\"nofollow noopener\">marketing digital<\/a>.<br \/>\nOs tr\u00eas <strong>KPIs de marketing<\/strong> que me concentrei incluem:<\/p>\n<ul>\n<li><strong>Crescimento do tr\u00e1fego<\/strong><\/li>\n<li><strong>Exposi\u00e7\u00e3o da marca na Pesquisa Google<\/strong><\/li>\n<li><strong>Gera\u00e7\u00e3o de leads<\/strong> OU vendas de autoatendimento<\/li>\n<\/ul>\n<h3 id=\"2-kpi-1---traffic-growth\">KPIs de marketing digital#1 &#8211; Crescimento do tr\u00e1fego<\/h3>\n<p>Se voc\u00ea \u00e9 como uma empresa on-line t\u00edpica, estar\u00e1 usando o Google Analytics.\u00a0O Google Analytics ou GA, resumidamente, \u00e9 a ferramenta de an\u00e1lise da web mais popular do mundo.<br \/>\nNa captura de tela abaixo, voc\u00ea pode ver facilmente que o tr\u00e1fego para este site aumentou desde o in\u00edcio do ano.<\/p>\n<p>O Relat\u00f3rio de vis\u00e3o geral do p\u00fablico-alvo \u00e9 o melhor relat\u00f3rio do GA para determinar se o n\u00famero de pessoas que visitam seu site cresceu no \u00faltimo X per\u00edodo de tempo.\u00a0Verifique se voc\u00ea est\u00e1 dando tempo suficiente, pois h\u00e1 efeitos sazonais e altera\u00e7\u00f5es no algoritmo do mecanismo de pesquisa do Google que podem resultar em varia\u00e7\u00f5es acima do normal.<\/p>\n<p>O uso do relat\u00f3rio de p\u00fablico-alvo da GA \u00e9 uma maneira simplista, por\u00e9m eficaz, de determinar se sua equipe de marketing \u00e9 bem-sucedida no aumento do tr\u00e1fego para seu site.<br \/>\nSe voc\u00ea tiver a op\u00e7\u00e3o de criar um\u00a0<a href=\"https:\/\/www.projectbi.net\/build-content-analytics-dashboard-google-analytics-tableau\/\" target=\"_blank\" rel=\"nofollow noopener\" aria-label=\" (abre em uma nova guia)\">painel de an\u00e1lise de conte\u00fado<\/a>\u00a0mais avan\u00e7ado\u00a0, eu recomendaria um aprofundamento no desempenho de canais espec\u00edficos, especialmente pesquisa org\u00e2nica e canais pagos.<\/p>\n<p>Se voc\u00ea notar que o tr\u00e1fego do seu GA n\u00e3o est\u00e1 aumentando, \u00e9 uma indica\u00e7\u00e3o clara de que a equipe de marketing n\u00e3o conseguiu dimensionar seus canais de marketing on-line. Se o tr\u00e1fego cresceu e os \u00fanicos canais que cresceram s\u00e3o canais pagos, voc\u00ea tamb\u00e9m tem um problema. \u00c9 raro uma empresa sustentar o crescimento a longo prazo apenas de canais pagos.<\/p>\n<h3>KPIs de marketing digital #2 &#8211; Exposi\u00e7\u00e3o da marca na Pesquisa do Google<\/h3>\n<p>O Google Search Console \u00e9 um site que fornece informa\u00e7\u00f5es detalhadas sobre o desempenho do seu site na pesquisa do Google.<\/p>\n<p>A ferramenta de relat\u00f3rios de desempenho \u00e9 interativa e, como voc\u00ea pode ver na captura de tela abaixo, pode filtrar para baixo para pesquisar consultas que contenham seu nome de marca.\u00a0Isso permite que voc\u00ea veja se o n\u00famero de impress\u00f5es, cliques e posi\u00e7\u00e3o no Google aumentou no \u00faltimo per\u00edodo X.<\/p>\n<p>Se a equipe de marketing estiver fazendo um excelente trabalho para aumentar o reconhecimento da marca, o n\u00famero de pessoas que pesquisam a marca no Google aumentar\u00e1. Voc\u00ea pode usar a ferramenta Google Search Console para verificar se o reconhecimento da sua marca no Google aumentou em 16 meses.<\/p>\n<h3 id=\"4-kpi-3---lead-gen-or-self-service-sales\">KPIs de marketing digital #3 &#8211; Gera\u00e7\u00e3o principal ou vendas de autoatendimento<\/h3>\n<p>A raz\u00e3o pela qual esse KPI de marketing \u00e9 a gera\u00e7\u00e3o de leads ou as vendas de autoatendimento \u00e9 porque diferentes empresas t\u00eam modelos diferentes. Em uma organiza\u00e7\u00e3o que possui uma equipe de vendas, a equipe de marketing s\u00f3 pode fazer muito para ajudar na venda. Em uma empresa com um modelo de autoatendimento (em que o usu\u00e1rio insere um cart\u00e3o de cr\u00e9dito e faz uma compra sem interagir com um representante de vendas), a conex\u00e3o entre a venda e a equipe de marketing est\u00e1 muito mais pr\u00f3xima.<\/p>\n<h4 id=\"5-how-to-measure-lead-gen\">Como medir a gera\u00e7\u00e3o de leads?<\/h4>\n<p>Para medir leads, basta agrupar os novos leads gerados por um per\u00edodo de data que fa\u00e7a sentido.\u00a0O caminho padr\u00e3o \u00e9 por m\u00eas.\u00a0Se voc\u00ea gerar um gr\u00e1fico semelhante ao mostrado abaixo, poder\u00e1 ver rapidamente se a equipe de marketing conseguiu aumentar o n\u00famero de leads dispon\u00edveis para vendas no \u00faltimo per\u00edodo X.<\/p>\n<p>Uma pergunta que voc\u00ea pode estar perguntando \u00e9 por que a medi\u00e7\u00e3o de tr\u00e1fego n\u00e3o \u00e9 suficiente?\u00a0O motivo pelo qual voc\u00ea deseja analisar a gera\u00e7\u00e3o de leads separadamente para o tr\u00e1fego \u00e9 porque pode haver fontes offline que geram leads.\u00a0Como nosso objetivo principal \u00e9 aumentar as vendas, o n\u00famero de leads gerados \u00e9 muito melhor para determinar se as vendas aumentar\u00e3o, pois est\u00e1 mais pr\u00f3ximo do ponto de convers\u00e3o no funil de vendas.\u00a0O tr\u00e1fego \u00e9 um direcionador de leads e leads s\u00e3o um direcionador de vendas.\u00a0Quanto mais pr\u00f3ximas nossas an\u00e1lises do final do funil, maior a precis\u00e3o poss\u00edvel na determina\u00e7\u00e3o do resultado final.<\/p>\n<h3 id=\"6-how-to-measure-self-service-sales\">Como medir as vendas de autoatendimento?<\/h3>\n<p>A melhor maneira de determinar se o marketing est\u00e1 melhorando seu desempenho em vendas de autoatendimento \u00e9 executando uma an\u00e1lise de coorte.<\/p>\n<p>Na captura de tela abaixo, voc\u00ea ver\u00e1 um exemplo dessa an\u00e1lise. Podemos ver que a porcentagem de usu\u00e1rios que adquiriram uma assinatura aumentou de 2% para mais de 7% nos \u00faltimos 6 meses. Isso indica para n\u00f3s que a qualidade do usu\u00e1rio aumentou significativamente nesse per\u00edodo.<\/p>\n<p>Voc\u00ea pode estar se perguntando: &#8220;mas Justin, e se o produto mudou muito durante esse per\u00edodo e mais usu\u00e1rios est\u00e3o encontrando valor com o servi\u00e7o do que antes?&#8221;. Esse \u00e9 um ponto v\u00e1lido e eu concordo que \u00e9 um esfor\u00e7o conjunto entre alguns departamentos que determinar\u00e1 se a taxa de convers\u00e3o entre usu\u00e1rios gratuitos e pagos aumenta.<\/p>\n<p>O motivo pelo qual ainda acho que essa \u00e9 uma boa maneira de medir o desempenho da equipe de marketing \u00e9 porque as revis\u00f5es em massa do produto s\u00e3o raras e essa vis\u00e3o normaliza o crescimento do usu\u00e1rio. O marketing ser\u00e1 r\u00e1pido em apontar que o n\u00famero de usu\u00e1rios aumentou, mas no final nos preocupamos com as vendas. Sim, o crescimento do usu\u00e1rio \u00e9 um impulsionador das vendas em uma empresa de autoatendimento, mas muitas vezes, voc\u00ea ver\u00e1 um aumento nos usu\u00e1rios e uma queda na taxa de compra. Isso n\u00e3o ajuda a organiza\u00e7\u00e3o.<\/p>\n<p>* Se voc\u00ea planeja criar essa visualiza\u00e7\u00e3o, defina uma restri\u00e7\u00e3o de tempo entre a inscri\u00e7\u00e3o e a compra. Se voc\u00ea n\u00e3o fizer isso, as coortes mais antigas ter\u00e3o uma vantagem injusta de mais tempo para a convers\u00e3o dos usu\u00e1rios. Voc\u00ea deseja definir um per\u00edodo em que 80% das vendas ocorram e depois ignorar as vendas que ocorrem fora desta janela. Isso torna cada coorte igual. Se o tempo entre o pagamento gratuito e o pagamento for muito longo, essa visualiza\u00e7\u00e3o n\u00e3o ser\u00e1 muito \u00fatil, pois voc\u00ea ter\u00e1 um longo atraso na determina\u00e7\u00e3o de seus n\u00fameros e isso tornar\u00e1 a visualiza\u00e7\u00e3o inativa.<\/p>\n<h2 id=\"7-summary\">Sum\u00e1rio<\/h2>\n<p>Existem algumas maneiras claras de usar os dados para medir o desempenho do seu departamento de marketing.\u00a0Os principais KPIs de marketing em que me concentro s\u00e3o o crescimento do tr\u00e1fego, a exposi\u00e7\u00e3o da marca no Google e o crescimento de leads ou vendas no \u00faltimo X per\u00edodo de tempo.<br \/>\nEu sei que este post pode irritar algumas pessoas. Se voc\u00ea n\u00e3o concordar comigo, escreva um coment\u00e1rio abaixo com seus pensamentos. Eu adoraria iniciar uma discuss\u00e3o e me permitir mudar de id\u00e9ia.<\/p>\n<p>Tradu\u00e7\u00e3o livre, do \u00f3timo blog da <a href=\"https:\/\/www.projectbi.net\/marketing-team-failing-how-prove-it\/\" target=\"_blank\" rel=\"nofollow noopener\">ProjectBi<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O cen\u00e1rio de marketing est\u00e1 se tornando cada vez mais complexo. Hoje, uma ORGANIZA\u00c7\u00c3O deve considerar uma ampla gama de op\u00e7\u00f5es para divulgar sua empresa. Os canais mais tradicionais, como an\u00fancios on-line, e-mail e marketing de conte\u00fado, est\u00e3o em constante evolu\u00e7\u00e3o e novas tecnologias, como por exemplo, VR est\u00e3o chegando muito em breve. Embora o [&hellip;]<\/p>\n","protected":false},"author":8496,"featured_media":20265,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"KPIs em Marketing Digital! Sua equipe de marketing est\u00e1 falhando, veja como voc\u00ea pode resolver isso. O cen\u00e1rio de marketing est\u00e1 se tornando cada vez mais complexo. ","_seopress_robots_index":"","footnotes":""},"categories":[496],"tags":[],"class_list":["post-20254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analise"],"_links":{"self":[{"href":"https:\/\/centoevinte.com.br\/portal-de-conteudo\/wp-json\/wp\/v2\/posts\/20254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centoevinte.com.br\/portal-de-conteudo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centoevinte.com.br\/portal-de-conteudo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centoevinte.com.br\/portal-de-conteudo\/wp-json\/wp\/v2\/users\/8496"}],"replies":[{"embeddable":true,"href":"https:\/\/centoevinte.com.br\/portal-de-conteudo\/wp-json\/wp\/v2\/comments?post=20254"}],"version-history":[{"count":22,"href":"https:\/\/centoevinte.com.br\/portal-de-conteudo\/wp-json\/wp\/v2\/posts\/20254\/revisions"}],"predecessor-version":[{"id":26432,"href":"https:\/\/centoevinte.com.br\/portal-de-conteudo\/wp-json\/wp\/v2\/posts\/20254\/revisions\/26432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centoevinte.com.br\/portal-de-conteudo\/wp-json\/wp\/v2\/media\/20265"}],"wp:attachment":[{"href":"https:\/\/centoevinte.com.br\/portal-de-conteudo\/wp-json\/wp\/v2\/media?parent=20254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centoevinte.com.br\/portal-de-conteudo\/wp-json\/wp\/v2\/categories?post=20254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centoevinte.com.br\/portal-de-conteudo\/wp-json\/wp\/v2\/tags?post=20254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}